{"id":184,"date":"2010-06-22T12:46:25","date_gmt":"2010-06-22T10:46:25","guid":{"rendered":"http:\/\/blog.alwaysdata.com\/?p=184"},"modified":"2018-02-01T16:35:12","modified_gmt":"2018-02-01T15:35:12","slug":"php-5-3-disponible","status":"publish","type":"post","link":"https:\/\/blog.alwaysdata.com\/fr\/2010\/06\/22\/php-5-3-disponible\/","title":{"rendered":"PHP 5.3 disponible"},"content":{"rendered":"<p><!--:fr-->Je sais que cette nouvelle r\u00e9jouira beaucoup d\u2019entre vous&nbsp;: PHP 5.3 est enfin disponible chez alwaysdata. Plus pr\u00e9cis\u00e9ment&nbsp;: la version 5.3.2 est d\u00e9sormais install\u00e9e et s\u00e9lectionnable dans l\u2019administration, ainsi que la 5.2.13 rajout\u00e9e au passage. Comme d\u2019habitude, rien ne change automatiquement&nbsp;: c\u2019est \u00e0&nbsp;vous de passer \u00e0&nbsp;5.3 volontairement, si vous le souhaitez. Les nouveaux comptes, eux, sont par d\u00e9faut en 5.3.<\/p>\n<p>Cette version aura mis du temps \u00e0&nbsp;\u00eatre disponible pour plusieurs raisons. La premi\u00e8re, c\u2019est que nous \u00e9tions tr\u00e8s occup\u00e9s par la nouvelle architecture, entre autres. La seconde, c\u2019est que le d\u00e9ploiement d\u2019une nouvelle version majeure d\u2019un langage (que ce soit PHP, Python ou Ruby) est une op\u00e9ration beaucoup plus compliqu\u00e9e qu\u2019il n\u2019y para\u00eet. Le support de plusieurs versions d\u2019un m\u00eame langage non compatibles entre elles (par exemple, PHP 5.2 et 5.3) demande de gros efforts de cohabitation, et m\u00eame des d\u00e9veloppements internes assez cons\u00e9quents. C\u2019est la raison pour laquelle alwaysdata est probablement l\u2019un des seuls h\u00e9bergeurs \u00e0&nbsp;vous proposer simultan\u00e9ment autant de versions diff\u00e9rentes de PHP, Python et&nbsp;Ruby.<\/p>\n<p>Message personnel \u00e0&nbsp;tous les Rubyistes&nbsp;: la version 1.9.1 est sur les rails, encore un peu de patience :)<!--:--><!--:en-->Je sais que cette nouvelle r\u00e9jouira beaucoup d\u2019entre vous&nbsp;: PHP 5.3 est enfin disponible chez alwaysdata. Plus pr\u00e9cis\u00e9ment&nbsp;: la version 5.3.2 est d\u00e9sormais install\u00e9e et s\u00e9lectionnable dans l\u2019administration, ainsi que la 5.2.13 rajout\u00e9e au passage. Comme d\u2019habitude, rien ne change automatiquement&nbsp;: c\u2019est \u00e0&nbsp;vous de passer \u00e0&nbsp;5.3 volontairement, si vous le souhaitez. Les nouveaux comptes, eux, sont par d\u00e9faut en 5.3.<\/p>\n<p>Cette version aura mis du temps \u00e0&nbsp;\u00eatre disponible pour plusieurs raisons. La premi\u00e8re, c\u2019est que nous \u00e9tions tr\u00e8s occup\u00e9s par la nouvelle architecture, entre autres. La seconde, c\u2019est que le d\u00e9ploiement d\u2019une nouvelle version majeure d\u2019un langage (que ce soit PHP, Python ou Ruby) est une op\u00e9ration beaucoup plus compliqu\u00e9e qu\u2019il n\u2019y para\u00eet. Le support de plusieurs versions d\u2019un m\u00eame langage non compatibles entre elles (par exemple, PHP 5.2 et 5.3) demande de gros efforts de cohabitation, et m\u00eame des d\u00e9veloppements internes assez cons\u00e9quents. C\u2019est la raison pour laquelle alwaysdata est probablement l\u2019un des seuls h\u00e9bergeurs \u00e0&nbsp;vous proposer simultan\u00e9ment autant de versions diff\u00e9rentes de PHP, Python et&nbsp;Ruby.<\/p>\n<p>Message personnel \u00e0&nbsp;tous les Rubyistes&nbsp;: la version 1.9.1 est sur les rails, encore un peu de patience&nbsp;:)<!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je sais que cette nouvelle r\u00e9jouira beaucoup d\u2019entre vous&nbsp;: PHP 5.3 est enfin disponible chez alwaysdata. Plus pr\u00e9cis\u00e9ment&nbsp;: la version 5.3.2 est d\u00e9sormais install\u00e9e et \u2026 <a class=\"read-more\" href=\"https:\/\/blog.alwaysdata.com\/fr\/2010\/06\/22\/php-5-3-disponible\/\">Keep reading<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[230],"tags":[142,183],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-uncategorized-fr","tag-langages-fr","tag-php-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.alwaysdata.com\/fr\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}